{"id":545,"date":"2008-06-21T16:38:00","date_gmt":"2008-06-21T14:38:00","guid":{"rendered":""},"modified":"2021-01-13T16:30:29","modified_gmt":"2021-01-13T15:30:29","slug":"sai-di-aver-studiato-troppo-lungo","status":"publish","type":"post","link":"https:\/\/triptofun.it\/index.php\/2008\/06\/21\/sai-di-aver-studiato-troppo-lungo\/","title":{"rendered":"Sai di aver studiato troppo a lungo fisiologia quando&#8230;"},"content":{"rendered":"\n<p class=\"M\">1. PSP per te non significa &#8220;Play Station Portable&#8221; ma &#8220;Post Synaptic Potential&#8221;<br>2. un tuo amico non ha fatto in tempo a dire &#8220;Forse devo cambiare gli occhiali&#8221; e tu ti sei messo a disegnare lenti e raggi di luce sul tavolo<br>3. per aprire una porta pensi agli impulsi in partenza dall&#8217;area premotoria frontale, all&#8217;area 4 alla via piramidale ed extrapiramidale del movimento e al controllo dei nuclei cerebellari<br>4. non riesci ad addormentarti se prima non pensi alla regolazione del ciclo sonno-veglia del tronco encefalico e quando ti sei addormentato sogni fasi REM e nRem<br>5. quando suona la sveglia il tuo primo pensiero \u00e8 se eri in fase REM o in fase II<br>6. frequenti Wernicke pi\u00f9 dei tuoi amici<br>7. hai sbattuto col mignolo del piede contro una porta, ma sei talmente stressato per il troppo studio che non ci hai neanche fatto caso, ma appena te ne accorgi tutto ci\u00f2 a cui pensi \u00e8 la via discendente dopaminergica del controllo del dolore<br>8. cerchi le risposte a tutte le domande della vita aprendo il Conti in una pagina a caso<br>9. non riesci pi\u00f9 a dar da mangiare al cane senza pensare a Pavlov e ai suoi riflessi condizionati<br>10. diagnostichi a te stesso un&#8217;afasia di conduzione perch\u00e8 quando parli sembra che gli altri pensino tu sia di un altro pianeta, in realt\u00e0 gli stavi spiegando per l&#8217;ennesima volta la regolazione ortosimpatica del diametro della pupilla.<br>11. Ti ritrovi a pensare quanto dev&#8217;essere figo fare il test della capacit\u00e0 vitale con la diluizione dell&#8217;azoto per parlare con la voce di topolino<br>12. non riesci pi\u00f9 a pisciare in pace senza pensare ai vari riflessi lombo-sacrali e tronco-encefalici, al nucleo di Onuf e al centro pontino della minzione.<br>13. dopo esserti ubriacato per placare le tue angosce pensi che dopo tutto \u00e8 un&#8217;ottima occasione per ripassare l&#8217;atassia e i sintomi di lesione cerebellare<br>14. rispondi a tutte le domande che ti vengono rivolte con V\/F<br>15. sai citare a memoria contenuto e concentrazione dei gas nel sangue, valori di flusso ematico regionale nei distretti pi\u00f9 disparati come il glomo carotideo, pressioni osmotiche, oncotiche, molarit\u00e0, molalit\u00e0, genesi, propagazione, contenuto, percentuale, voltaggio di pressocch\u00e8 ogni molecola del corpo, ma ti accorgi di non sapere pi\u00f9 il tuo indirizzo, numero di telefono e data di nascita. a maggior ragione dimentichi i compleanni degli amici che ovviamente non accettano come giustificazione &#8220;Ho dovuto far posto al valore normale e patologico dell&#8217;indice di Tiffenau&#8221;<br>16. all&#8217;ultima festa a cui hai partecipato ti sei presentato senza pensarci come Jan Purkinje. Poi ovviamente sei dovuto scappare per studiare il giorno dopo<br>17. hai lanciato il gatto dei vicini dal balcone per studiare dal vivo la catena di riflessi che lo fa cadere in piedi (poi ti sei ricordato che abiti sopra la tangenziale)<br>18. ti \u00e8 capitato pi\u00f9 volte di pensare: per svoltare a destra devo attivare la corteccia motoria sinistra, la via piramidale che decussa e passa a destra, il motoneurone flessorio dell&#8217;avambraccio destro che riferisce afferenze al nucleo olivare sinistro che proietta al cervelletto destro che rif\u00e0 la strada al contrario&#8230;.. e poi giri a sinistra<br>19. sei pronto a saltare alla gola di chiunque pronunci l&#8217;avverbio &#8220;fisiologicamente&#8221;<br>20. stai seriamente meditando il suicidio ma poi pensi che<br>&#8211; non deve essere piacevole restare in preda agli spasmi muscolari da stricnina<br>&#8211; il curaro \u00e8 ancora peggio: cadi a terra come una pera e non hai pi\u00f9 il controllo del corpo, muori soffocato<br>&#8211; forse si potrebbe meditare di tagliarsi le vene, cos\u00ec da sperimentare anche il famoso riflesso del barocettore carotideo&#8230;. poi vieni sviato dai tuoi intenti perch\u00e8 tutto questo ti ricorda che devi ancora ripassare lo shock ipovolemico<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1. PSP per te non significa &#8220;Play Station Portable&#8221; ma &#8220;Post Synaptic Potential&#8221;2. un tuo amico non ha fatto in tempo a dire &#8220;Forse devo cambiare gli occhiali&#8221; e tu ti sei messo a disegnare lenti e raggi di luce sul tavolo3. per aprire una porta pensi agli impulsi in [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":546,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[55,48,12,54,14],"tags":[3,25,30],"_links":{"self":[{"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/posts\/545"}],"collection":[{"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/comments?post=545"}],"version-history":[{"count":2,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/posts\/545\/revisions"}],"predecessor-version":[{"id":1060,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/posts\/545\/revisions\/1060"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/media\/546"}],"wp:attachment":[{"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/media?parent=545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/categories?post=545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/tags?post=545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}