{"id":509,"date":"2009-05-05T17:26:00","date_gmt":"2009-05-05T15:26:00","guid":{"rendered":""},"modified":"2021-01-04T09:03:22","modified_gmt":"2021-01-04T08:03:22","slug":"il-punto-blu-di-psichiatria-e-la","status":"publish","type":"post","link":"https:\/\/triptofun.it\/index.php\/2009\/05\/05\/il-punto-blu-di-psichiatria-e-la\/","title":{"rendered":"Il punto blu di psichiatria e la selezione darwiniana"},"content":{"rendered":"\n<p class=\"M\">Lasciatemi passare per ripetitiva, ma la sessione esami si avvicina e, da buona previdente, ho cercato di stampare gli statini degli esami prossimi venturi.<br>Sapendo come funzionano le cose nella nostra facolt\u00e0 ho fatto ricorso alle superiori conoscenze degli studenti pi\u00f9 anziani per farmi spiegare l\u2019ubicazione del punto blu pi\u00f9 vicino. La spiegazione \u00e8 stata all\u2019incirca:<br>\u201cEntra dal passo carrabile di via Cherasco, vai a destra senza entrare nell\u2019ospedale, nel cortile trovi le scale che portano all\u2019aula magna di psichiatria, sali, giri a destra e prendi il primo ascensore. Premi 2 e ti porta al quarto piano, esci ti fai aprire la porta del reparto, giri a sinistra e poi a destra e sei arrivato\u201d.<br>Sembra facile e infatti lo \u00e8 per la media delle indicazioni dell\u2019ospedale. Per\u00f2, mentre cerco di seguire a memoria le indicazioni scavalcando cavi e altre apparecchiature abbandonate, mi viene da pensare a chi possa essere venuto in mente di situare l\u2019unica macchinetta stampa-statini nell\u2019arco di un paio di chilometri in un posto cos\u00ec assurdo. Ora non dico che avrebbero dovuto affiancarla al bancomat san Paolo all\u2019ingresso, ma da l\u00ec al quarto piano di psichiatria ci sono delle sensate vie di mezzo; anche senza troppo sforzo di immaginazione si pensa facilmente a un milione di posti pi\u00f9 comodi dello stretto corridoio pinzato tra due reparti psichiatrici al quarto piano di un\u2019ala secondaria dell\u2019ospedale.<br>Quindi ho pensato che ci dovesse essere un motivo ragionevole per siffatta decisione e, con un\u2019accelerazione ideica forse ispirata dal luogo, in attesa del mio turno per stampare, sono riuscita a scovarne uno. Ebbene la mia spiegazione \u00e8 la selezione darwiniana.<br>Pensateci, per riuscire nell\u2019impresa di trovare il punto blu e stampare gli statini sono necessarie innumerevoli doti:<br>&#8211; per prima cosa bisogna avere ottime conoscenze quali studenti degli anni precedenti o medici del reparto, con le sole indicazioni della guida dello studente \u00e8 matematicamente impossibile trovare la malefica macchinetta.<br>&#8211; Altrettanto indispensabile \u00e8 un ottimo senso dell\u2019orientamento (per motivi strettamente correlati all\u2019architettura dell\u2019ospedale di cui parleremo diffusamente pi\u00f9 avanti \u00e8 estremamente facile perdersi).<br>&#8211; Non guastano una discreta prontezza di riflessi per dribblare pazienti psicotici e caposala infuriate, pazienza infinita (perch\u00e9 sembrer\u00e0 impossibile ma c\u2019\u00e8 coda), discrete capacit\u00e0 informatiche (come ogni punto blu che si rispetti non funziona quasi mai).<br>Ne consegue che solo i migliori, quelli che posseggono tutte le caratteristiche su menzionate o quelli pi\u00f9 fortunati che causalmente si imbattono nel punto blu, riescano a sopravvivere, a stampare gli statini e a completare la propria carriera universitaria, tutti gli altri soccombono all\u2019impietosa legge della selezione naturale.<br>Sospetto che gli pneumococchi all\u2019epoca di Fleming abbiano avuto vita pi\u00f9 facile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lasciatemi passare per ripetitiva, ma la sessione esami si avvicina e, da buona previdente, ho cercato di stampare gli statini degli esami prossimi venturi.Sapendo come funzionano le cose nella nostra facolt\u00e0 ho fatto ricorso alle superiori conoscenze degli studenti pi\u00f9 anziani per farmi spiegare l\u2019ubicazione del punto blu pi\u00f9 vicino. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":510,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[55,12,14],"tags":[3,30],"_links":{"self":[{"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/posts\/509"}],"collection":[{"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/comments?post=509"}],"version-history":[{"count":3,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/posts\/509\/revisions"}],"predecessor-version":[{"id":1030,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/posts\/509\/revisions\/1030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/media\/510"}],"wp:attachment":[{"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/media?parent=509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/categories?post=509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/tags?post=509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}