{"id":1199,"date":"2022-01-28T10:41:00","date_gmt":"2022-01-28T09:41:00","guid":{"rendered":"https:\/\/triptofun.it\/?p=1199"},"modified":"2022-04-01T10:45:29","modified_gmt":"2022-04-01T08:45:29","slug":"benvenuta-omicron","status":"publish","type":"post","link":"https:\/\/triptofun.it\/index.php\/2022\/01\/28\/benvenuta-omicron\/","title":{"rendered":"Benvenuta Omicron"},"content":{"rendered":"\n<p class=\"M\">25 dicembre 2021.<br>La popolazione del Pronto soccorso covid si divide in due categorie: un certo numero di vaccinati con mal di gola, naso che cola, dolori muscolari che viene a farsi il tampone perch\u00e9 \u201cnon si sa mai\u201d e lo scopre inaspettatamente positivo e un certo numero di non vaccinati con la tosse, la febbre e la mancanza di fiato che ha palesemente scritto covid in fronte.<br>Benvenuta Omicron.<br><br>La signora S., 50 anni, in attesa della terza dose, mi chiede cosa fare con i parenti che ha visto al cenone ieri sera: \u00abAvevo pure fatto un tampone il 23 per vederli tranquilla ed era negativo! E poi ho solo il mal di gola, \u00e8 possibile che sia covid? Non \u00e8 il caso che mi facciate un molecolare che magari \u00e8 un falso positivo?\u00bb. Vorrei lasciarle questa illusione, ma \u00e8 la quinta in poche ore con gli stessi sintomi e il tampone positivo. Quanto meno sta bene, alla cena erano tutti vaccinati e i suoi genitori avevano gi\u00e0 fatto la terza dose. Non posso per\u00f2 fare a meno di pensare che il sistema di sorveglianza (mai efficace) salter\u00e0 in queste vacanze. Solo con quelli che ho diagnosticato stamattina e i loro contatti stretti ci sono un centinaio di persone in isolamento a Torino, che dovrebbero tutte fare un tampone entro l\u2019Epifania, con i medici di base in vacanza, le farmacie prese d\u2019assedio da chi ha prenotato i tamponi per vedere in sicurezza i parenti e dai non vaccinati che necessitano del green pass.<br><br>K., 40 anni, non vaccinata, sa gi\u00e0 di avere il covid, il che mi porta a chiedermi cosa la spinga in Pronto soccorso la mattina di Natale. \u00abMi sento molto stanca\u00bb. I parametri sono normali, l\u2019ecografia pure, d\u2019altra parte la spossatezza da covid \u00e8 cosa nota, dopo 15 giorni dovrebbe saperlo anche lei. \u00abPerch\u00e9 non si \u00e8 vaccinata?\u00bb, chiede l\u2019infermiere a fianco a me (io da tempo ho imparato che \u00e8 meglio non chiedere per preservare la salute del mio fegato). \u00abSono contraria e in ogni caso tornassi indietro non mi vaccinerei e non mi vacciner\u00f2\u00bb. Ecco, in questi momenti penso che questi soggetti, gi\u00e0 che costano ai contribuenti due viaggi in ambulanza e lo stipendio mio e degli altri dipendenti il giorno di Natale, dovrebbero quanto meno perdere il diritto al mugugno. Come nei contratti di marineria genovese del \u2018300: ti pago di pi\u00f9 ma stai zitto e non ti lamenti. Non ti vaccini, ti ammali, costi il triplo al sistema sanitario, almeno non ti lagni dei pochi sintomi che hai la fortuna di avere.<br><br>Chi mugugna tantissimo, ma a buon diritto, \u00e8 R. Nella barella a fianco. Lui ha 70 anni, \u00e8 vaccinato, ma ha una malattia ematologica che gli sopprime il sistema immunitario e ha scoperto oggi di avere la polmonite da covid. Non sembra grave, ma contando la necessit\u00e0 di ossigeno e i fattori di rischio dobbiamo ricoverarlo. Il suo cruccio \u00e8 la moglie con il tumore dei polmoni, che ha paura di aver contagiato e che per ora \u00e8 a casa in isolamento. \u00abNon capisco, ho fatto tre dosi di vaccino, sono uscito di casa solo per portare mia moglie a fare la chemio, cos\u2019altro potevo fare?\u00bb.<\/p>\n\n\n\n<p class=\"M\">20 gennaio 2022.<br>In Pronto covid le barelle dei positivi sono ammucchiate una sull\u2019altra, non c\u2019\u00e8 letteralmente spazio per passare a visitarli, bisogna aprirsi un varco come in quegli schedari montati sui binari, dove si pu\u00f2 accedere a uno scaffale per volta. I posti letto per i ricoveri saltano fuori con il contagocce e per ogni ricoverato c\u2019\u00e8 qualcun altro da tenere, da una settimana abbiamo 15 pazienti in una stanza pensata per accoglierne 4, con le prolunghe dell\u2019ossigeno spinte al massimo e le bombole da riempire pi\u00f9 volte al giorno. D\u2019altro canto i posti letto covid regionali sono stati dimezzati, ed \u00e8 impensabile invertire il Pronto soccorso\u00a0<em>pulito<\/em>\u00a0con quello\u00a0<em>sporco<\/em>\u00a0perch\u00e9 gli accessi al Pronto\u00a0<em>pulito<\/em>\u00a0sono tanti quanti quelli del Pronto covid. Non avremmo dove mettere i malati, non abbiamo pi\u00f9 reparti da sacrificare, abbiamo gi\u00e0 compresso tutte le chirurgie in un unico piano, decentralizzando le urgenze meno complesse. Se la coperta era corta l\u2019inverno scorso, quest\u2019anno \u00e8 proprio finita, come finita \u00e8 la pazienza degli operatori. I chirurghi non ne possono pi\u00f9 di fare un lavoro che non \u00e8 il loro, gli infermieri sono esausti di inzuppare a ogni turno la divisa dentro a una tuta di plastica, tutti sono stufi di veder morire la gente. Poco cambia se \u00e8 l\u2019ennesima polmonite da covid o se \u00e8 il tumore del polmone che a causa di un ritardo nella lista operatoria si \u00e8 disseminato e non ha pi\u00f9 possibilit\u00e0 di guarire, il fatto \u00e8 che la campagna vaccinale ha ridotto i ricoveri tra i vaccinati, ma non ha fermato il virus e gli ospedali restano pieni.<br><br>C., 83 anni, Alzheimer, non vaccinata, ha la febbre da 8 giorni, ma la stavano curando con degli antibiotici pensando fosse un\u2019infezione delle vie urinarie. Questa sera sembrava pi\u00f9 soporosa del solito e la figlia ha chiamato l\u2019ambulanza. Saturazione d\u2019ossigeno infima, ecografia polmonare orribile: ha una polmonite da covid da manuale. Mi preparo a una telefonata uguale ad altre mille fatte in questi due anni: \u00abSua mamma ha una polmonite molto grave, non risponde all\u2019ossigeno, non ha indicazioni alla terapia intensiva perch\u00e9 \u00e8 troppo debilitata, la tratteremo ma ci sono poche speranze\u00bb. La risposta a sua volta non mi giunge nuova: \u00abMa quindi non la vedr\u00f2 pi\u00f9?\u00bb. Qui, nel corso di questi due anni, le risposte, sulla base di un astruso algoritmo composto da numero di contagi, leggi, editti della direzione, grado di affollamento, sono state nell\u2019ordine \u00abNo\u00bb, \u00abForse\u00bb, \u00abS\u00ec (se ha il green pass)\u00bb, \u00abPer questa volta facciamo un\u2019eccezione\u00bb, \u00abAssolutamente no\u00bb. Oggi \u00e8 il caso dell\u2019ultima\u2026 tralasciando che la mamma ha il covid e che fargliela vedere implicherebbe guidarla nella vestizione, tralasciando l\u2019assoluto divieto all\u2019ingresso dei parenti formulato dalla direzione dell\u2019ospedale, posso mai far entrare un parente in questo inferno di barelle ammucchiate? \u00abBeh, allora le chiedo se pu\u00f2 andare all\u2019orecchio di mia mamma e dirle che la saluta sua figlia R., so che sembra che non capisca, ma a me risponde, \u00e8 importante\u00bb.<\/p>\n\n\n\n<p class=\"M\"><br>Intanto al centro vaccinale si cerca di erodere una minima quota di non vaccinati, una prima dose alla volta. C\u2019\u00e8 chi \u00e8 sfuggito alle maglie per qualche scaricabarile medico-legale, magari perch\u00e9 ha avuto un effetto collaterale da un farmaco e il medico vaccinatore non se la sentiva di vaccinarlo senza il parere dell\u2019allergologo, il quale rimandava la palla al reumatologo che la rispediva al vaccinatore in un loop che si pu\u00f2 interrompere solo trovando qualcuno disposto una buona volta ad assumersi un rischio infimo a fronte di un beneficio nettamente superiore (vista la contagiosit\u00e0 di Omicron). C\u2019\u00e8 chi si \u00e8 convinto, ma mica tanto, e si fa venire una crisi di panico lamentando dolori ovunque prima ancora dell\u2019iniezione. C\u2019\u00e8 chi, ancora in piedi e con la giacca addosso, chiede: \u00abChe vaccino mi fate?\u00bb Come se fossimo in una profumeria. Ho cos\u00ec scoperto il razzismo contro Moderna, che ha sostituito AstraZeneca nell\u2019olimpo dei vaccini sgraditi e l\u2019entusiasmo per Novavax, l\u2019unico ancora non disponibile (sar\u00e0 lo stesso meccanismo che guida il desiderio dell\u2019introvabile playstation 5?). A fine giornata la pila delle prime e seconde dosi somministrate \u00e8 neanche un quinto di quella delle terze, l\u2019impressione che ne traggo \u00e8 che abbiamo raggiunto il massimo livello di vaccinati in un paese democratico con il nostro livello di disinformazione. Nessun obbligo vaccinale pu\u00f2 convincere gente che, ricoverata in terapia subintensiva con la polmonite da covid, rifiuta le terapie perch\u00e9 si cura solo con l\u2019aloe o ritiene di aver fatto bene a non vaccinarsi: \u00abPerch\u00e9 tanto io me lo sono preso da un vaccinato\u00bb (il quale per\u00f2 evidentemente \u00e8 a casa propria col raffreddore).<br><br>Ma se i tracciamenti hanno fallito, come \u00e8 inevitabile con un virus dall\u2019altissima contagiosit\u00e0 e dal brevissimo tempo di raddoppio, la campagna vaccinale si avvicina all\u2019asintoto orizzontale, come se ne esce? Sono settimane che mi pongo questa domanda senza risposta. L\u2019unica speranza ragionevole sarebbe che tutti i non immunizzati si ammalassero e guarissero, auspicabilmente; a quel punto potremmo passare a gestire il covid \u2013 se non varier\u00e0 ulteriormente \u2013 come gestivamo l\u2019influenza, ossia con campagne vaccinali poco partecipate, ignorando i contagi intraospedalieri e accettando un minimo numero di ricoveri e decessi annui per malattia grave. Due anni di pandemia hanno poi aumentato notevolmente la consapevolezza della popolazione nei confronti delle malattie infettive: chi mai nel 2019 si preoccupava di non vedere qualcuno o non andare a lavorare perch\u00e9 aveva la febbre? E chi mai avrebbe pensato di farsi un tampone diagnostico in casa per un raffreddore? Ora invece \u00e8 buona abitudine, anche tra vaccinati, evitare di frequentarsi o lavorare da casa al minimo sintomo, premurarsi di effettuare un tampone prima di cenare al ristorante o di affrontare un viaggio. Tutto ci\u00f2 \u00e8 senza dubbio positivo, ma non basta e richiede un ripensamento della sanit\u00e0, degli ospedali, di risorse e spazi al momento assenti, nonch\u00e9 una gestione che, in futuro, non sconti i medesimi ritardi: il tracciamento \u00e8 partito tardi, quando le mutazioni del virus l\u2019hanno reso difficilissimo, ed \u00e8 tuttora gestito in modo farraginoso; i percorsi covid sono stati improvvisati a ogni singola ondata, come se si trattasse di un\u2019eterna imprevedibile emergenza, anzich\u00e9 di un\u2019endemia ad andamento stagionale.<br><br>Se \u00e8 ora di pensare a una convivenza di medio-lungo termine con questo virus, \u00e8 alle strategie potenzialmente applicabili a future pandemie e alla prevenzione delle malattie infettive in generale che si deve, in tutta la loro seriet\u00e0, in questo momento guardare.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Post originariamente pubblicato su<a href=\"https:\/\/volerelaluna.it\/in-primo-piano\/2022\/01\/28\/benvenuta-omicron\/\"> Volere la luna<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>25 dicembre 2021.La popolazione del Pronto soccorso covid si divide in due categorie: un certo numero di vaccinati con mal di gola, naso che cola, dolori muscolari che viene a farsi il tampone perch\u00e9 \u201cnon si sa mai\u201d e lo scopre inaspettatamente positivo e un certo numero di non vaccinati [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[55,15,12],"tags":[2,64],"_links":{"self":[{"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/posts\/1199"}],"collection":[{"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/comments?post=1199"}],"version-history":[{"count":2,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/posts\/1199\/revisions"}],"predecessor-version":[{"id":1201,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/posts\/1199\/revisions\/1201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/media\/33"}],"wp:attachment":[{"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/media?parent=1199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/categories?post=1199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/triptofun.it\/index.php\/wp-json\/wp\/v2\/tags?post=1199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}